{"id":1763,"date":"2020-10-13T15:05:06","date_gmt":"2020-10-13T20:05:06","guid":{"rendered":"https:\/\/www.feyalegria.org\/guatemala\/?p=1763"},"modified":"2023-09-20T14:24:16","modified_gmt":"2023-09-20T19:24:16","slug":"abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/","title":{"rendered":"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row enable_first_overlay=\u00bbtrue\u00bb first_overlay_opacity=\u00bb1&#8243; first_background_color=\u00bb#df5461&#8243; css=\u00bb.vc_custom_1614220964145{padding-top: 40px !important;}\u00bb][vc_column width=\u00bb2\/3&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2141 alignleft\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3-300x300.png 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3-150x150.png 150w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3-200x200.png 200w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>En el marco del D\u00eda Internacional de la Ni\u00f1a y de la campa\u00f1a La Luz de las Ni\u00f1as, promovido por Fe y Alegr\u00eda Guatemala y Entreculturas se realiz\u00f3 en espacio virtual Abramos Di\u00e1logo: \u201cLa Sombra de la Violencia en las Ni\u00f1as\u201d con el fin de visibilizar la violencia, discriminaci\u00f3n y desigualdad que sufren las ni\u00f1as en Guatemala y el mundo.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Guatemala, ha sido catalogado como el peor pa\u00eds para ser mujer en Am\u00e9rica Latina y las ni\u00f1as, en especial ind\u00edgenas, son las m\u00e1s vulnerables. Diariamente, se registran m\u00e1s de 200 partos en ni\u00f1as y adolescentes de 10 a 19 a\u00f1os producto de una violaci\u00f3n.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El evento cont\u00f3 con la participaci\u00f3n de Raquel Mart\u00edn, de Entreculturas -Fe y Alegr\u00eda Espa\u00f1a-, quien enfatiz\u00f3 que \u201ctodos los tipos de violencia que sufren las ni\u00f1as y mujeres no son azar sino un flagelo sistem\u00e1tico y estructural que ocurre en todo el mundo y en todos los contextos sociales\u201d. Por su lado, Mar\u00eda Jos\u00e9 P\u00e9rez de UNESCO en Guatemala, remarc\u00f3 datos de la situaci\u00f3n de las ni\u00f1as en el pa\u00eds, mostrando que son las mujeres las que m\u00e1s sufren la discriminaci\u00f3n educativa en el mundo. En Guatemala, la media de escolaridad de las mujeres en el pa\u00eds es de 4 a\u00f1os mientras que para la mujer ind\u00edgena es de tan solo 2.6 a\u00f1os.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Un ejemplo de vida, ha sido Kimberly Chival\u00e1n, la \u201cNi\u00f1a Colibr\u00ed\u201d, quien tuvo que dejar la escuela a los 12 a\u00f1os para ayudar en la econom\u00eda familiar. Su deseo de seguir estudiando hizo que buscara formas de reinsertarse en la escuela, 4 a\u00f1os despu\u00e9s encontr\u00f3 en Fe y Alegr\u00eda la posibilidad de hacerlo. A pesar de que su padre se neg\u00f3 a que ella continuara estudiando, en su testimonio coment\u00f3 que \u00e9l le cuestion\u00f3 \u201c\u00bfPara qu\u00e9 vas a estudiar? T\u00fa sabes la necesidad que tenemos, adem\u00e1s vos sos mujer y despu\u00e9s te vas a casar\u201d. Su deseo de cumplir sus sue\u00f1os, la llev\u00f3 a estudiar a escondidas de su padre. Con grandes dificultades, pero con el apoyo de su madre y su fuerte convicci\u00f3n, Kim a\u00fan sigue luchando por lograr su meta, siendo tambi\u00e9n inspiraci\u00f3n y ejemplo de superaci\u00f3n para ni\u00f1as y j\u00f3venes que atraviesan por los mismos problemas que ella.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El programa de La Luz de las Ni\u00f1as pretende visibilizar la situaci\u00f3n de violencia que sufren las ni\u00f1as, empoderarlas y mejorar su autoestima, crear espacios de protecci\u00f3n dentro y fuera de la escuela e incidir para transformar las causas de esta injusticia. Por eso, el P. Miquel Cort\u00e9s, SJ, director de Fe y Alegr\u00eda Guatemala enfatiz\u00f3 la necesidad de privilegiar con una educaci\u00f3n integral y transformadora a favor de las ni\u00f1as prioriz\u00e1ndolas en los procesos formativos y de inserci\u00f3n social; \u201c\u2026debemos desarrollar programas como \u2018La Luz de las Ni\u00f1as\u00b4 o \u2018Protagonismo Juvenil Organizado\u2019 para la construcci\u00f3n de sociedades m\u00e1s justas y equitativas en favor de las ni\u00f1as y adolescentes; debemos ser esa luz que disipa las tinieblas\u201d.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243; css=\u00bb.vc_custom_1598395418937{padding-top: 30px !important;padding-left: 20px !important;background-color: #f3f3f3 !important;border-radius: 10px !important;}\u00bb][vc_widget_sidebar sidebar_id=\u00bbnicdark_sidebar\u00bb][vc_btn title=\u00bbM\u00e1s noticias\u00bb style=\u00bbcustom\u00bb custom_background=\u00bb#cc0000&#8243; custom_text=\u00bb#ffffff\u00bb shape=\u00bbround\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.feyalegria.org%2Fguatemala%2Factualidad%2F|title:Novedades\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 240px\"> El programa de La Luz de las Ni\u00f1as pretende visibilizar la situaci\u00f3n de violencia que sufren las ni\u00f1as, empoderarlas y mejorar su autoestima, crear espacios de protecci\u00f3n dentro y fuera de la escuela e incidir para&#8230;<\/div>\n","protected":false},"author":20,"featured_media":2141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[9],"tags":[],"post_folder":[],"class_list":["post-1763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d - #SomosFeyAlegr\u00eda en Guatemala<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d - #SomosFeyAlegr\u00eda en Guatemala\" \/>\n<meta property=\"og:description\" content=\"El programa de La Luz de las Ni\u00f1as pretende visibilizar la situaci\u00f3n de violencia que sufren las ni\u00f1as, empoderarlas y mejorar su autoestima, crear espacios de protecci\u00f3n dentro y fuera de la escuela e incidir para...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/\" \/>\n<meta property=\"og:site_name\" content=\"#SomosFeyAlegr\u00eda en Guatemala\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-13T20:05:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-20T19:24:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adminpefya01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminpefya01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/\"},\"author\":{\"name\":\"adminpefya01\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/#\\\/schema\\\/person\\\/47298f14fdde36b788fa7e2388626a19\"},\"headline\":\"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d\",\"datePublished\":\"2020-10-13T20:05:06+00:00\",\"dateModified\":\"2023-09-20T19:24:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/\"},\"wordCount\":649,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2020\\\/08\\\/24213525\\\/Fotos-Hn-500x500-3.png\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/\",\"name\":\"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d - #SomosFeyAlegr\u00eda en Guatemala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2020\\\/08\\\/24213525\\\/Fotos-Hn-500x500-3.png\",\"datePublished\":\"2020-10-13T20:05:06+00:00\",\"dateModified\":\"2023-09-20T19:24:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/#\\\/schema\\\/person\\\/47298f14fdde36b788fa7e2388626a19\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2020\\\/08\\\/24213525\\\/Fotos-Hn-500x500-3.png\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2020\\\/08\\\/24213525\\\/Fotos-Hn-500x500-3.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/\",\"name\":\"#SomosFeyAlegr\u00eda en Guatemala\",\"description\":\"Movimiento de Educaci\u00f3n Popular y Promoci\u00f3n Social\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/#\\\/schema\\\/person\\\/47298f14fdde36b788fa7e2388626a19\",\"name\":\"adminpefya01\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/guatemala\\\/author\\\/adminpefya01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d - #SomosFeyAlegr\u00eda en Guatemala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/","og_locale":"es_ES","og_type":"article","og_title":"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d - #SomosFeyAlegr\u00eda en Guatemala","og_description":"El programa de La Luz de las Ni\u00f1as pretende visibilizar la situaci\u00f3n de violencia que sufren las ni\u00f1as, empoderarlas y mejorar su autoestima, crear espacios de protecci\u00f3n dentro y fuera de la escuela e incidir para...","og_url":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/","og_site_name":"#SomosFeyAlegr\u00eda en Guatemala","article_published_time":"2020-10-13T20:05:06+00:00","article_modified_time":"2023-09-20T19:24:16+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png","type":"image\/png"}],"author":"adminpefya01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminpefya01","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/"},"author":{"name":"adminpefya01","@id":"https:\/\/www.feyalegria.org\/guatemala\/#\/schema\/person\/47298f14fdde36b788fa7e2388626a19"},"headline":"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d","datePublished":"2020-10-13T20:05:06+00:00","dateModified":"2023-09-20T19:24:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/"},"wordCount":649,"image":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/","url":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/","name":"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d - #SomosFeyAlegr\u00eda en Guatemala","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png","datePublished":"2020-10-13T20:05:06+00:00","dateModified":"2023-09-20T19:24:16+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/#\/schema\/person\/47298f14fdde36b788fa7e2388626a19"},"breadcrumb":{"@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/17\/2020\/08\/24213525\/Fotos-Hn-500x500-3.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.feyalegria.org\/guatemala\/abramos-dialogo-la-sombra-de-la-violencia-en-las-ninas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.feyalegria.org\/guatemala\/"},{"@type":"ListItem","position":2,"name":"Abramos di\u00e1logo: \u201cLa sombra de la violencia en las ni\u00f1as\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/guatemala\/#website","url":"https:\/\/www.feyalegria.org\/guatemala\/","name":"#SomosFeyAlegr\u00eda en Guatemala","description":"Movimiento de Educaci\u00f3n Popular y Promoci\u00f3n Social","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/guatemala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/guatemala\/#\/schema\/person\/47298f14fdde36b788fa7e2388626a19","name":"adminpefya01","url":"https:\/\/www.feyalegria.org\/guatemala\/author\/adminpefya01\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/posts\/1763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/comments?post=1763"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/posts\/1763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/media\/2141"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/media?parent=1763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/categories?post=1763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/tags?post=1763"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/guatemala\/wp-json\/wp\/v2\/post_folder?post=1763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}