{"id":11484,"date":"2025-10-30T22:14:37","date_gmt":"2025-10-30T22:14:37","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=11484"},"modified":"2025-10-31T16:30:31","modified_gmt":"2025-10-31T16:30:31","slug":"evangelizacion-por-radio-es-posible","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/","title":{"rendered":"Evangelizaci\u00f3n por radio \u00bfes posible?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<h1><b>Evangelizaci\u00f3n por radio \u00bfes posible?<\/b><\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=\u00bb11487&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right;\"><strong>Alexander Medina |<\/strong> Periodista RNR Fe y Alegr\u00eda<\/p>\n<p style=\"text-align: right;\"><strong>Fotos<\/strong> <b> | <\/b>Equipos de El Tigre y Subdirecci\u00f3n de Pastoral<\/p>\n<p>[\/vc_column_text][vc_separator css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\">Desde el a\u00f1o 2022 en la Red Nacional de Radio Fe y Alegr\u00eda Noticias, (RNRFyA) nos propusimos entrar en un proceso de discernimiento para definir qu\u00e9 tipo de Fe quer\u00edamos impulsar en nuestros contenidos, en nuestra programaci\u00f3n nacional, con sus respectivas expresiones locales,\u00a0 y desde la l\u00f3gica multiplataforma, como servicio comunicacional a todas nuestras audiencias.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11485 alignleft\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-scaled.jpg\" alt=\"\" width=\"351\" height=\"234\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-scaled.jpg 2560w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-300x200.jpg 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-1024x683.jpg 1024w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-768x512.jpg 768w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-1536x1024.jpg 1536w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215120\/Tucupita-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/p>\n<p style=\"text-align: justify;\">Una de las premisas iniciales es que la Evangelizaci\u00f3n, entendida como la propagaci\u00f3n de la Palabra de Dios, con sentido eclesial, en comunidad y hacia \u201clas gentes excluidas, descartadas por este mundo\u201d y con especial \u00e9nfasis en la opci\u00f3n preferencial por los pobres (m\u00e1xima apuesta de la Iglesia latinoamericana) y los j\u00f3venes.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n partimos desde la convicci\u00f3n y la pr\u00e1ctica, desde nuestra fundaci\u00f3n en 1975, que de origen y por naturaleza las radios de Fe y Alegr\u00eda son Evangelizadoras. En principio, eso significaba que todo lo que se piensa, se dice, se hace, est\u00e1 inspirado en comunicar la Buena Noticia, anclado en la espiritualidad ignaciana, al ser nuestro Movimiento de Educaci\u00f3n Popular y Promoci\u00f3n Social una obra de la Compa\u00f1\u00eda de Jes\u00fas en Venezuela.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>En este sentido:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022<\/strong> Una radio Evangelizadora que ense\u00f1a, anima, acompa\u00f1a, motiva,\u00a0 educa, capacita, forma, sirve, monitorea, rinde y pide cuentas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>El mensaje de Jes\u00fas debe ba\u00f1ar toda la programaci\u00f3n: informativa, educativa musical, cultural, de opini\u00f3n, deportiva, de manera creativa, que enganche y atraiga.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que acompa\u00f1a procesos de crecimiento humano \u2013 cristianos en diferentes \u00e1mbitos de la sociedad venezolana, en red, junto a otros y otras, en l\u00f3gica de colaboraci\u00f3n y complementariedad.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que forma y practica el ejercicio de la ciudadan\u00eda con los valores del Reino de Dios, de Jes\u00fas de Nazaret: justicia, paz, solidaridad, fraternidad, servicio, inclusi\u00f3n, reconciliaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que ofrece contenidos que ayudan a pensar y formar la mentalidad ciudadana a favor del bien com\u00fan, a trav\u00e9s de su variada programaci\u00f3n: informaci\u00f3n, entrevistas, charlas, conferencias, seminarios en vivo, transmisiones, radio foros, podcast, en vivo a trav\u00e9s de plataformas de TikTok, Instagram, Facebook, etc.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que es Evangelizada en su interior, porque forma y acompa\u00f1a a sus equipos para tales fines. Que ora, reflexiona y discierne a partir de la Buena Nueva.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que garantiza un ambiente de familiaridad, unidad, solidaridad y fraternidad.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio enamorada de la gente, alegre, fresca, festiva; que siembra esperanza y liberaci\u00f3n.\u00a0 Que llora, se conduele y tambi\u00e9n celebra la esperanza de la gente, del pueblo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que promueve una responsable, solidaria y fraterna convivencia en los barrios, en los caser\u00edos, urbanizaciones, comunidades populares, ind\u00edgenas. Promoviendo el bien com\u00fan para todos, el amor al pr\u00f3jimo, manifestado\u00a0 en la conformaci\u00f3n de\u00a0 comunidades organizadas en funci\u00f3n de sus propias necesidades y la vivencia de la fe cristiana (comunidades cristianas de vida y servicio a los m\u00e1s necesitados, a los pobres, a los excluidos en las nuevas fronteras).<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que ayuda a formar\u00a0 familias sanas, saludables, amorosas, custodias, defensoras, protectoras, solidarias, unidas fraternas, serviciales, humanas, cristianas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que sea \u00fatil a la gente: que propone temas para la discusi\u00f3n familiar y comunitaria, en pro de sus intereses: ciudadan\u00eda, valores para la convivencia, la importancia de la pol\u00edtica, la democracia, el cuidado de la Casa Com\u00fan, la creaci\u00f3n, la salud la educaci\u00f3n, las relaciones fraternas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que promueve y visibiliza la defensa, protecci\u00f3n y exigencia de los Derechos Humanos, denuncia las injusticias y todo lo que atente en contra del Reino de Fraternidad y Amor. Es una radio prof\u00e9tica que anuncia y denuncia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio que est\u00e1 siempre en ACCI\u00d3N SOLIDARIA con la gente, las organizaciones, las parroquias, las comunidades, las escuelas de Fe y Alegr\u00eda y otras instituciones, para promover la solidaridad social.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Es una radio Evangelizadora, que sea un lugar de encuentro, que acoge y difunde la identidad cultural de sus pueblos; de la ciudad y sus comunidades. Que responde al desaf\u00edo de desarrollo educativo y misionero.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>\u2022 <\/strong>Estas definiciones tambi\u00e9n est\u00e1n renovadas y contenidas, como marco conceptual orientador e inspirador, en el nuevo Proyecto Pol\u00edtico Comunicacional de Radio Fe y Alegr\u00eda Noticias.<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: justify;\">\u00bfQu\u00e9 productos tenemos al aire en estos momentos?<\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><b><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11486 alignright\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215519\/WhatsApp-Image-2025-10-14-at-7.40.40-PM.jpeg\" alt=\"\" width=\"363\" height=\"272\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215519\/WhatsApp-Image-2025-10-14-at-7.40.40-PM.jpeg 1080w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215519\/WhatsApp-Image-2025-10-14-at-7.40.40-PM-300x225.jpeg 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215519\/WhatsApp-Image-2025-10-14-at-7.40.40-PM-1024x768.jpeg 1024w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30215519\/WhatsApp-Image-2025-10-14-at-7.40.40-PM-768x576.jpeg 768w\" sizes=\"auto, (max-width: 363px) 100vw, 363px\" \/><b><b><b><b>1. Bienvenido a tu Casa<\/b><span style=\"font-weight: 400;\">: <\/span><\/b><\/b><\/b><\/b>El programa semanal Bienvenido a Tu Casa es el espacio emblem\u00e1tico, bandera de la dimensi\u00f3n de evangelizaci\u00f3n en la Red Nacional de Radio Fe y Alegr\u00eda. Sus contenidos expl\u00edcitos de la Buena Nueva en Venezuela, fundamentalmente, y en Am\u00e9rica Latina, est\u00e1n enfocados desde la acci\u00f3n social de la Iglesia, a trav\u00e9s de sus di\u00f3cesis, parroquias, comunidades eclesiales de bases, organizaciones sociales como C\u00e1ritas; pastorales como la Comisi\u00f3n Episcopal de Educaci\u00f3n; su similar de Derechos Humanos; movimientos juveniles, etc.; y, por supuesto, por lo que va proponiendo y motorizando la Provincia de la Compa\u00f1\u00eda de Jes\u00fas en Venezuela. En este marco conceptual, nuestro Movimiento Fe y Alegr\u00eda se incorpora y se compromete con este anuncio, comunicado, de la construcci\u00f3n del Reino de Dios en esta tierra de Gracia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Por tanto, Bienvenido a Tu Casa es un espacio de denuncia, de anuncio, de propuesta, de invitaci\u00f3n, de sue\u00f1os compartidos a la luz del Evangelio de Jes\u00fas de Nazareth para una sociedad m\u00e1s justa, fraterna, reconciliada,\u00a0 esperanzada, dignificada. Se convierte en la apuesta principal de Radio Fe y Alegr\u00eda Noticias en su programaci\u00f3n nacional radiof\u00f3nica, cada domingo, de 8 a 10:00 a.m.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>2. Una Palabra Oportuna:<\/strong><span style=\"font-weight: 400;\"> Es una producci\u00f3n diaria, de lunes a domingo, en formato audio, con una reflexi\u00f3n narrada por varios integrantes del Movimiento y sacerdotes jesuitas colaboradores. Desde Una Palabra Oportuna (UPO), seguimos acompa\u00f1ando desde el\u00a0 amor incondicional del Se\u00f1or para con todos sus hijos; de la reconciliaci\u00f3n y de la urgente necesidad de la reconstrucci\u00f3n de una fraternidad humana desde el seguimiento a Cristo Jes\u00fas; del perd\u00f3n sincero y aut\u00e9ntico; de la paz duradera y no la de in\u00fatiles tratados y falsos acuerdos; del reconocimiento del otro; del caminar juntos en la co-construcci\u00f3n del Reino de Justicia, Amor, Igualdad, Fraternidad y de la Esperanza.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>3. Transmisiones Marianas y de Religiosidad Popular:<\/strong><span style=\"font-weight: 400;\"> Una de las vertientes de manifestaci\u00f3n de la fe cat\u00f3lica en la programaci\u00f3n y producci\u00f3n de la RNRFyA que hemos potenciado en los \u00faltimos 3 a\u00f1os tiene que ver con la transmisi\u00f3n en vivo de las festividades marianas en varias localidades venezolanas. En las emblem\u00e1ticas celebraciones de la Divina Pastora (Barquisimeto); Nuestra Se\u00f1ora de la Consolaci\u00f3n de T\u00e1riba (T\u00e1chira); Virgen del Valle (Oriente); Virgen del Rosario de Chiquinquir\u00e1 (Zulia) e Inmaculada Concepci\u00f3n (Caracas), acompa\u00f1amos las s\u00faplicas, las peticiones, las oraciones, las devociones, los clamores y los buenos deseos de los feligreses que ven en la Madre de Dios, y desde su fe sencilla y humilde, la principal intercesora ante el Dios de la vida y la esperanza.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>4. Otras producciones:<\/strong><span style=\"font-weight: 400;\"> Es menester mencionar que nuestras plataformas comunicacionales no solo se traducen en estas transmisiones sino tambi\u00e9n entrevistas especiales, notas web, reels de Instagram y otras producciones digitales. Justamente esos son los formatos que hemos potenciado con las producciones especiales sobre la canonizaci\u00f3n de los dos primeros santos venezolanos Jos\u00e9 Gregorio Hern\u00e1ndez y Carmen Rendiles.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n es digno destacar las coberturas especiales que hicimos en los momentos de la muerte del Papa Francisco, su sepelio, el nombramiento del nuevo pont\u00edfice Le\u00f3n XIV, incluyendo las deliberaciones previas de los Cardenales.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Desde la Red de Radios Jesuitas de Am\u00e9rica Latina y El Caribe, a la que pertenece la RNRFyA, compartimos producci\u00f3n y transmisi\u00f3n del programa En Buena Compa\u00f1\u00eda que visibiliza las buenas acciones de obras, redes, centros de acci\u00f3n social, Provincias de la Compa\u00f1\u00eda de Jes\u00fas en esta regi\u00f3n. Tambi\u00e9n el espacio semanal es una oportunidad para denunciar en los diferentes pa\u00edses violaciones de derechos humanos, perjuicio a la Creaci\u00f3n, a la Casa Com\u00fan, a la dignidad de las personas, apuntalados estos testimonios por las cuatro preferencias apost\u00f3licas de la Compa\u00f1\u00eda de Jes\u00fas: 1) dar a conocer a Dios; 2) caminar al lado de los descartados, de los marginados; 3) acompa\u00f1ar a los j\u00f3venes en sus sue\u00f1os; y 4) cuidado de la Casa Com\u00fan.<\/p>\n<p>[\/vc_column_text][vc_column_inner alignment=\u00bbcenter\u00bb][\/vc_column_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right;\"><strong>31 de octubre de 2025<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 265px\">Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios<\/div>\n","protected":false},"author":86,"featured_media":11487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[746,141,13],"tags":[1497,622,721,448],"post_folder":[],"class_list":["post-11484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin-interno","category-educacion","category-irfa","tag-aniversario-50-anos","tag-educomunicacion","tag-radio-fe-y-alegria","tag-venezuela"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evangelizaci\u00f3n por radio \u00bfes posible?<\/title>\n<meta name=\"description\" content=\"Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evangelizaci\u00f3n por radio \u00bfes posible?\" \/>\n<meta property=\"og:description\" content=\"Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T22:14:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T16:30:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30220713\/VISITA-DE-RELIQUIAS-JGH.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminvefya04\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminvefya04\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/\"},\"author\":{\"name\":\"adminvefya04\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/219fd6083ed3d63f6ac623e175a02e29\"},\"headline\":\"Evangelizaci\u00f3n por radio \u00bfes posible?\",\"datePublished\":\"2025-10-30T22:14:37+00:00\",\"dateModified\":\"2025-10-31T16:30:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/\"},\"wordCount\":1580,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/30220713\\\/VISITA-DE-RELIQUIAS-JGH.jpeg\",\"keywords\":[\"Aniversario 50 a\u00f1os\",\"Educomunicaci\u00f3n\",\"Radio Fe y Alegr\u00eda\",\"Venezuela\"],\"articleSection\":[\"Bolet\u00edn Interno\",\"Educaci\u00f3n\",\"IRFA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/\",\"name\":\"Evangelizaci\u00f3n por radio \u00bfes posible?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/30220713\\\/VISITA-DE-RELIQUIAS-JGH.jpeg\",\"datePublished\":\"2025-10-30T22:14:37+00:00\",\"dateModified\":\"2025-10-31T16:30:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/219fd6083ed3d63f6ac623e175a02e29\"},\"description\":\"Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/evangelizacion-por-radio-es-posible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/30220713\\\/VISITA-DE-RELIQUIAS-JGH.jpeg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/30220713\\\/VISITA-DE-RELIQUIAS-JGH.jpeg\",\"width\":1080,\"height\":810},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/219fd6083ed3d63f6ac623e175a02e29\",\"name\":\"adminvefya04\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/adminvefya04\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evangelizaci\u00f3n por radio \u00bfes posible?","description":"Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/","og_locale":"es_ES","og_type":"article","og_title":"Evangelizaci\u00f3n por radio \u00bfes posible?","og_description":"Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios","og_url":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2025-10-30T22:14:37+00:00","article_modified_time":"2025-10-31T16:30:31+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30220713\/VISITA-DE-RELIQUIAS-JGH.jpeg","type":"image\/jpeg"}],"author":"adminvefya04","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminvefya04","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/"},"author":{"name":"adminvefya04","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/219fd6083ed3d63f6ac623e175a02e29"},"headline":"Evangelizaci\u00f3n por radio \u00bfes posible?","datePublished":"2025-10-30T22:14:37+00:00","dateModified":"2025-10-31T16:30:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/"},"wordCount":1580,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30220713\/VISITA-DE-RELIQUIAS-JGH.jpeg","keywords":["Aniversario 50 a\u00f1os","Educomunicaci\u00f3n","Radio Fe y Alegr\u00eda","Venezuela"],"articleSection":["Bolet\u00edn Interno","Educaci\u00f3n","IRFA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/","url":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/","name":"Evangelizaci\u00f3n por radio \u00bfes posible?","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30220713\/VISITA-DE-RELIQUIAS-JGH.jpeg","datePublished":"2025-10-30T22:14:37+00:00","dateModified":"2025-10-31T16:30:31+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/219fd6083ed3d63f6ac623e175a02e29"},"description":"Todas las radios de Fe y Alegr\u00eda mantienen una programaci\u00f3n evangelizadora, siendo el centro la Palabra de Dios","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/evangelizacion-por-radio-es-posible\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30220713\/VISITA-DE-RELIQUIAS-JGH.jpeg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/10\/30220713\/VISITA-DE-RELIQUIAS-JGH.jpeg","width":1080,"height":810},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/219fd6083ed3d63f6ac623e175a02e29","name":"adminvefya04","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/adminvefya04\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/11484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=11484"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/11484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/11487"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=11484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=11484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=11484"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=11484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}