{"id":11629,"date":"2025-11-12T14:43:55","date_gmt":"2025-11-12T14:43:55","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=11629"},"modified":"2025-11-12T15:38:55","modified_gmt":"2025-11-12T15:38:55","slug":"fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/","title":{"rendered":"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \u00abvitrina agroecol\u00f3gica\u00bb de biodiversidad"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<h1><b>Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \u00abvitrina agroecol\u00f3gica\u00bb de biodiversidad<\/b><\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=\u00bb11632&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right\"><b>Shirley G\u00f3mez | <\/b><span style=\"font-weight: 400\">Referente de Comunicaci\u00f3n de Fe y Alegr\u00eda EduComunicaci\u00f3n\u00a0<\/span><\/p>\n<p style=\"text-align: right\"><b>Elluz Pern\u00eda | <\/b><span style=\"font-weight: 400\">Directora de Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n<\/span><\/p>\n<p style=\"text-align: right\"><b>Fotos: <\/b><span style=\"font-weight: 400\">EduComunicaci\u00f3n Santa Elena de Uair\u00e9n\u00a0<\/span><\/p>\n<p>[\/vc_column_text][vc_separator css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify\">El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Asimismo, promueve la asociaci\u00f3n de cultivos en el conuco, incluyendo yuca acompa\u00f1ada de lechosas, batata, leguminosas, cambur y plantas silvestres, logrando as\u00ed un espacio de policultivo y biodiversidad.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11635 alignleft\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12143630\/WhatsApp-Image-2025-11-10-at-10.47.27-AM-1.jpeg\" alt=\"\" width=\"395\" height=\"296\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12143630\/WhatsApp-Image-2025-11-10-at-10.47.27-AM-1.jpeg 1080w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12143630\/WhatsApp-Image-2025-11-10-at-10.47.27-AM-1-300x225.jpeg 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12143630\/WhatsApp-Image-2025-11-10-at-10.47.27-AM-1-1024x768.jpeg 1024w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12143630\/WhatsApp-Image-2025-11-10-at-10.47.27-AM-1-768x576.jpeg 768w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/>Esta pr\u00e1ctica se implementa bajo la perspectiva ancestral de la etnia Pem\u00f3n, y en ella participan 22 estudiantes de la menci\u00f3n Agroecolog\u00eda con el fin de ampliar sus conocimientos para el cuidado de Keserak Chiiwon (Madre Tierra). El proyecto se desarrolla en el Aula de Aprendizaje (ADA) de Agua Fr\u00eda y el Centro de Agroecolog\u00eda Yui Yeremep\u00f6 (CAE), con el apoyo de la comunidad y el acompa\u00f1amiento de la ONG La Cosecha.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Esta iniciativa, implementada desde el 2021, ha alcanzado hasta la fecha un 80% de su objetivo con el establecimiento de sistemas agroforestales alrededor de la escuela Fe y Alegr\u00eda y cerca de los hogares de algunos habitantes.<\/p>\n<p>&nbsp;<\/p>\n<h4>T\u00e9cnicas y objetivos<\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Ha sido fundamental el uso de biofertilizantes y t\u00e9cnicas de manejo del suelo (como la cobertura muerta) para sustituir la tala y quema, m\u00e9todos que eran utilizados tradicionalmente por los nativos. Estos, progresivamente, han adoptado t\u00e9cnicas como el uso de rastrojo y las siembras cercanas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">El equipo se plante\u00f3 como objetivo principal recuperar las \u00e1reas degradadas mediante la implementaci\u00f3n de un sistema agroforestal Taurepan, buscando la armon\u00eda con la naturaleza para proteger los r\u00edos y otros reservorios de agua.<\/p>\n<p>&nbsp;<\/p>\n<h4>Fortalecimiento de conocimientos<\/h4>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11631 alignright\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140114\/FOTO-APOYO-3.jpg\" alt=\"\" width=\"359\" height=\"269\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140114\/FOTO-APOYO-3.jpg 1200w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140114\/FOTO-APOYO-3-300x225.jpg 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140114\/FOTO-APOYO-3-1024x768.jpg 1024w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140114\/FOTO-APOYO-3-768x576.jpg 768w\" sizes=\"auto, (max-width: 359px) 100vw, 359px\" \/>Este proceso ha sido de ense\u00f1anza-aprendizaje integral, permitiendo a los participantes conocer las pr\u00e1cticas tradicionales y los nuevos m\u00e9todos. De esta manera, han podido equilibrar y fortalecer sus conocimientos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Como resultado, ha sido posible la plantaci\u00f3n de 2 mil matas, logrando que muchas de estas sirvan como corredores ambientales entre r\u00edos y bosques para reforestar las orillas de los aluviones.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Por ello, el equipo contin\u00faa trabajando en la necesidad de visibilizar los beneficios del sistema agroforestal para lograr una mayor aceptaci\u00f3n comunitaria.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Otro de los prop\u00f3sitos centrales de este proyecto es consolidar al centro como un centro vitrina agroecol\u00f3gica, as\u00ed como revalorizar la cultura Pem\u00f3n y su sabidur\u00eda ancestral como base para el cuidado del territorio.<\/p>\n<p>[\/vc_column_text][vc_column_inner alignment=\u00bbcenter\u00bb][\/vc_column_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: right\"><strong>13 de noviembre de 2025<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 265px\">Con el objetivo de cuidar la madre tierra y mantener la sustentabilidad alimentaria a trav\u00e9s de la siembra de varios rubros, el centro educativo de Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, desde hace 4 a\u00f1os implementa un proyecto con el que se ha convertido en una \u00abvitrina ecol\u00f3gica\u00bb<\/div>\n","protected":false},"author":86,"featured_media":11630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[746,13],"tags":[1513,1517,1519],"post_folder":[],"class_list":["post-11629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin-interno","category-irfa","tag-casa-comun","tag-etniia-pemon","tag-vitrina-ecologica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una &quot;vitrina agroecol\u00f3gica&quot; de biodiversidad - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"description\" content=\"El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una &quot;vitrina agroecol\u00f3gica&quot; de biodiversidad - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T14:43:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-12T15:38:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140110\/FOTO-PORTADA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminvefya04\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminvefya04\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/\"},\"author\":{\"name\":\"adminvefya04\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/219fd6083ed3d63f6ac623e175a02e29\"},\"headline\":\"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \u00abvitrina agroecol\u00f3gica\u00bb de biodiversidad\",\"datePublished\":\"2025-11-12T14:43:55+00:00\",\"dateModified\":\"2025-11-12T15:38:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/\"},\"wordCount\":576,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/12140110\\\/FOTO-PORTADA.jpg\",\"keywords\":[\"Casa com\u00fan\",\"Etn\u00edia Pem\u00f3n\",\"Vitrina Ecol\u00f3gica\"],\"articleSection\":[\"Bolet\u00edn Interno\",\"IRFA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/\",\"name\":\"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \\\"vitrina agroecol\u00f3gica\\\" de biodiversidad - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/12140110\\\/FOTO-PORTADA.jpg\",\"datePublished\":\"2025-11-12T14:43:55+00:00\",\"dateModified\":\"2025-11-12T15:38:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/219fd6083ed3d63f6ac623e175a02e29\"},\"description\":\"El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/12140110\\\/FOTO-PORTADA.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/12140110\\\/FOTO-PORTADA.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/219fd6083ed3d63f6ac623e175a02e29\",\"name\":\"adminvefya04\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/adminvefya04\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \"vitrina agroecol\u00f3gica\" de biodiversidad - Fe y Alegr\u00eda en Venezuela","description":"El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/","og_locale":"es_ES","og_type":"article","og_title":"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \"vitrina agroecol\u00f3gica\" de biodiversidad - Fe y Alegr\u00eda en Venezuela","og_description":"El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.","og_url":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2025-11-12T14:43:55+00:00","article_modified_time":"2025-11-12T15:38:55+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140110\/FOTO-PORTADA.jpg","type":"image\/jpeg"}],"author":"adminvefya04","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminvefya04","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/"},"author":{"name":"adminvefya04","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/219fd6083ed3d63f6ac623e175a02e29"},"headline":"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \u00abvitrina agroecol\u00f3gica\u00bb de biodiversidad","datePublished":"2025-11-12T14:43:55+00:00","dateModified":"2025-11-12T15:38:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/"},"wordCount":576,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140110\/FOTO-PORTADA.jpg","keywords":["Casa com\u00fan","Etn\u00edia Pem\u00f3n","Vitrina Ecol\u00f3gica"],"articleSection":["Bolet\u00edn Interno","IRFA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/","url":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/","name":"Fe y Alegr\u00eda transforma su centro en Santa Elena de Uair\u00e9n en una \"vitrina agroecol\u00f3gica\" de biodiversidad - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140110\/FOTO-PORTADA.jpg","datePublished":"2025-11-12T14:43:55+00:00","dateModified":"2025-11-12T15:38:55+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/219fd6083ed3d63f6ac623e175a02e29"},"description":"El centro educativo Fe y Alegr\u00eda EduComunicaci\u00f3n en Santa Elena de Uair\u00e9n, una poblaci\u00f3n ubicada en el estado Bol\u00edvar, en la frontera con Brasil, implementa siembras de especies nativas como el moriche, guama y le\u00f1osas, adem\u00e1s de cilantro, ceboll\u00edn y lechuga.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/fe-y-alegria-transforma-su-centro-en-santa-elena-de-uairen-en-una-vitrina-agroecologica-de-biodiversidad\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140110\/FOTO-PORTADA.jpg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/11\/12140110\/FOTO-PORTADA.jpg","width":1200,"height":900},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/219fd6083ed3d63f6ac623e175a02e29","name":"adminvefya04","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/adminvefya04\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/11629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=11629"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/11629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/11630"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=11629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=11629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=11629"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=11629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}