{"id":2270,"date":"2021-01-15T17:09:03","date_gmt":"2021-01-15T17:09:03","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=2270"},"modified":"2021-01-16T00:04:58","modified_gmt":"2021-01-16T00:04:58","slug":"maestros-el-don-de-servir","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/","title":{"rendered":"Maestros: el don de servir"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row css=\u00bb.vc_custom_1606160684358{padding-top: 40px !important;}\u00bb][vc_column width=\u00bb5\/6&#8243;]\n    <div style=\"text-align:\" class=\"nd_options_section\">\n      <img decoding=\"async\" alt=\"\" style=\"width:\" class=\" nd_options_margin_0 nd_options_padding_0 \" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg\">\n    <\/div>\n   [vc_row_inner][vc_column_inner width=\u00bb3\/4&#8243;][vc_column_text]<\/p>\n<p>\n\u201cEn todo Amar y Servir\u201d, dijo alguna vez San Ignacio de Loyola, fundador de la Compa\u00f1\u00eda de Jes\u00fas. Una frase poderosa que, de aplicarla, la vida ser\u00eda menos compleja.<\/p>\n<p>Esa vocaci\u00f3n de servicio la refleja Lettyzaida Zerpa, promotora educativa del Instituto Radiof\u00f3nico Fe y Alegr\u00eda (IRFA) en el estado M\u00e9rida.<\/p>\n<p>\u201cCuando no me puedo comunicar con ellos (sus alumnos), por el tema de la luz o las conexiones, voy directamente a sus casas; los visito, les pregunto, les ayudo e incluso les brindo palabras de aliento para seguir adelante\u201d, dice.<\/p>\n<p>Puedes leer la historia completa de Letty haciendo <a href=\"https:\/\/www.radiofeyalegrianoticias.com\/el-don-de-servir\/\" rel=\"noopener noreferrer\" target=\"_blank\">clic aqu\u00ed<\/a>.<\/p>\n<p>Para conocer otras historias de nuestros maestros puedes ingresar <a href=\"https:\/\/www.radiofeyalegrianoticias.com\/category\/rededucacion\/\" rel=\"noopener noreferrer\" target=\"_blank\">aqu\u00ed<\/a>.<\/p>\n<p>[\/vc_column_text][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00bb1\/6&#8243; css=\u00bb.vc_custom_1606160506628{background-color: #e3e3e3 !important;border-radius: 15px !important;}\u00bb][vc_widget_sidebar sidebar_id=\u00bbnicdark_sidebar\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 264px\">\u201cEn todo Amar y Servir\u201d, dijo alguna vez San Ignacio de Loyola, fundador de la Compa\u00f1\u00eda de Jes\u00fas. Una frase poderosa que, de aplicarla, la vida ser\u00eda menos compleja. Esa es la vocaci\u00f3n de Lettyzaida Zerpa.<\/div>\n","protected":false},"author":90,"featured_media":2251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[13],"tags":[398,400],"post_folder":[],"class_list":["post-2270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-irfa","tag-dia-del-maestro","tag-fe-y-alegria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maestros: el don de servir - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maestros: el don de servir - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"\u201cEn todo Amar y Servir\u201d, dijo alguna vez San Ignacio de Loyola, fundador de la Compa\u00f1\u00eda de Jes\u00fas. Una frase poderosa que, de aplicarla, la vida ser\u00eda menos compleja. Esa es la vocaci\u00f3n de Lettyzaida Zerpa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T17:09:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-16T00:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminfyaven\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminfyaven\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/\"},\"author\":{\"name\":\"adminfyaven\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/7fcf310cf79e9dfc0cf304f520691604\"},\"headline\":\"Maestros: el don de servir\",\"datePublished\":\"2021-01-15T17:09:03+00:00\",\"dateModified\":\"2021-01-16T00:04:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/\"},\"wordCount\":191,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/01\\\/15151024\\\/SERVIR-696x381-1.jpg\",\"keywords\":[\"D\u00eda del Maestro\",\"Fe y Alegr\u00eda\"],\"articleSection\":[\"IRFA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/\",\"name\":\"Maestros: el don de servir - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/01\\\/15151024\\\/SERVIR-696x381-1.jpg\",\"datePublished\":\"2021-01-15T17:09:03+00:00\",\"dateModified\":\"2021-01-16T00:04:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/7fcf310cf79e9dfc0cf304f520691604\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/maestros-el-don-de-servir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/01\\\/15151024\\\/SERVIR-696x381-1.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/01\\\/15151024\\\/SERVIR-696x381-1.jpg\",\"width\":696,\"height\":381,\"caption\":\"Foto: Fe y Alegr\u00eda.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/7fcf310cf79e9dfc0cf304f520691604\",\"name\":\"adminfyaven\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/adminfyaven\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maestros: el don de servir - Fe y Alegr\u00eda en Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/","og_locale":"es_ES","og_type":"article","og_title":"Maestros: el don de servir - Fe y Alegr\u00eda en Venezuela","og_description":"\u201cEn todo Amar y Servir\u201d, dijo alguna vez San Ignacio de Loyola, fundador de la Compa\u00f1\u00eda de Jes\u00fas. Una frase poderosa que, de aplicarla, la vida ser\u00eda menos compleja. Esa es la vocaci\u00f3n de Lettyzaida Zerpa.","og_url":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2021-01-15T17:09:03+00:00","article_modified_time":"2021-01-16T00:04:58+00:00","og_image":[{"width":696,"height":381,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg","type":"image\/jpeg"}],"author":"adminfyaven","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminfyaven","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/"},"author":{"name":"adminfyaven","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/7fcf310cf79e9dfc0cf304f520691604"},"headline":"Maestros: el don de servir","datePublished":"2021-01-15T17:09:03+00:00","dateModified":"2021-01-16T00:04:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/"},"wordCount":191,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg","keywords":["D\u00eda del Maestro","Fe y Alegr\u00eda"],"articleSection":["IRFA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/","url":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/","name":"Maestros: el don de servir - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg","datePublished":"2021-01-15T17:09:03+00:00","dateModified":"2021-01-16T00:04:58+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/7fcf310cf79e9dfc0cf304f520691604"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/maestros-el-don-de-servir\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2021\/01\/15151024\/SERVIR-696x381-1.jpg","width":696,"height":381,"caption":"Foto: Fe y Alegr\u00eda."},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/7fcf310cf79e9dfc0cf304f520691604","name":"adminfyaven","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/adminfyaven\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/2270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=2270"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/2270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/2251"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=2270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=2270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=2270"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=2270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}