{"id":3599,"date":"2022-04-28T08:50:07","date_gmt":"2022-04-28T08:50:07","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=3599"},"modified":"2022-04-29T02:34:37","modified_gmt":"2022-04-29T02:34:37","slug":"gracias-abraham-y-patricia","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/","title":{"rendered":"Gracias, Abraham y Patricia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column]<div style=\"background-color:;height: 30px\" class=\"nicdark_section  \"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29001954\/Abraham-y-Patricia-Reyes-web.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3600 alignleft\" src=\"https:\/\/www.feyalegria.org\/wp-content\/uploads\/sites\/4\/2022\/04\/7-Foto-AyP.jpg\" alt=\"\" width=\"329\" height=\"468\" \/><\/a>En la d\u00e9cada de los a\u00f1os setenta, del siglo pasado, conoc\u00ed a Abraham. Me ayudaba en la reparaci\u00f3n de un equipo de impresi\u00f3n offset que ten\u00edamos en el Jes\u00fas Obrero. Era cuidadoso, analizaba muy bien el problema y pon\u00eda todo su empe\u00f1o y saber pr\u00e1ctico en resolverlo y entregar la m\u00e1quina funcionando. No ten\u00eda apuro en terminar, porque lo que le importaba era hacer bien su trabajo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">M\u00e1s adelante, cuando ya empieza a formarse para ser ordenado como di\u00e1cono permanente, ven\u00eda con frecuencia a nuestra comunidad, para planificar su apostolado con el Padre D\u00edaz Guill\u00e9n, p\u00e1rroco de Jes\u00fas Obrero. Nunca entendi\u00f3 su ordenaci\u00f3n como una dignidad que le separaba de sus hermanos, ni se sent\u00eda de otra categor\u00eda. Entendi\u00f3 al pie de la letra, sin glosa, que ser di\u00e1cono era ser servidor. Cercano a Dios y cercano a su gente. Ejemplo de laico y ejemplo de ordenado, caminando al lado de todos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">En aquellos primeros a\u00f1os, yo todav\u00eda no sab\u00eda que Fe y Alegr\u00eda hab\u00eda nacido en la casa que \u00e9l y Patricia hab\u00edan regalado al Padre V\u00e9laz. Y despu\u00e9s de todos estos a\u00f1os estoy convencido que todas las Fe y Alegr\u00eda extendidas por el mundo son fruto de la semilla de su generosidad. La generosidad del pobre, como me gusta decir, es la que produce frutos de Reino. La del que da, sin esperar nada a cambio. Generosidad unida a una confianza grande en la providencia de Dios, porque sabe que, si cuida de los p\u00e1jaros y las flores, mucho m\u00e1s cuidar\u00e1 de sus hijos m\u00e1s peque\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Este gesto de Abraham y Patricia no fue improvisado. Les sali\u00f3 del coraz\u00f3n porque ten\u00edan un coraz\u00f3n generoso, capaz de abrirse a las necesidades de sus hermanos y de ver el bien com\u00fan antes que el personal: Si me quedo con la casa ser\u00e1 solo la casa de mis hijos, pero si la convertimos en escuela ser\u00e1 la casa de todos los ni\u00f1os del barrio. El Padre V\u00e9laz, al recibirla nos dice: Este fue el don inapreciable que nos hizo Abraham Reyes; \u00e9l ha sido el motor del pensamiento y de la acci\u00f3n de Fe y Alegr\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Estoy seguro de que el Padre V\u00e9laz y Fe y Alegr\u00eda aprendieron de este gesto, que hoy es parte del ADN del Movimiento. Sus maestros y personal son reflejo de esa misma generosidad y compromiso, incluso en estos tiempos de tantas carencias y dificultades. Y por eso tambi\u00e9n, todas las escuelas extendidas, por ahora, por 22 pa\u00edses y tres continentes, tienen que contar en sus or\u00edgenes y durante toda su existencia con el aporte generoso de la comunidad. Es la condici\u00f3n para que se haga patente el Esp\u00edritu, para que Fe y Alegr\u00eda sea un Movimiento con Esp\u00edritu, para que Fe y Alegr\u00eda perviva siendo esperanza para el pobre.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Al agradecer a Patricia y Abraham por su generosidad y su testimonio, estamos agradeciendo al Esp\u00edritu de Dios que sigue presente y activo en Fe y Alegr\u00eda, en nuestra Iglesia\u2026 y m\u00e1s all\u00e1\u2026<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Y en este momento \u2013necesariamente limitado\u2013 de agradecimientos, debo agradecer a mi compa\u00f1ero y amigo Joseba Lazcano que nos ha recogido todos estos materiales sobre Abraham y Patricia. Me consta que lo ha hecho con la fe y la alegr\u00eda muy propias de nuestro Movimiento.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\">Manuel J. Aristorena, s.j.<\/p>\n<p style=\"text-align: right\">Director Nacional Fe y Alegr\u00eda Venezuela<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_btn title=\u00bbDescargar libro\u00bb style=\u00bbcustom\u00bb custom_background=\u00bb#aa0f16&#8243; custom_text=\u00bb#ffffff\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fd3pugrm67vf9n7.cloudfront.net%2Fwp-content%2Fuploads%2Fsites%2F4%2F2022%2F04%2F29001954%2FAbraham-y-Patricia-Reyes-web.pdf|target:_blank\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 265px\">Al agradecer a Patricia y Abraham por su generosidad y su testimonio, estamos agradeciendo al Esp\u00edritu de Dios que sigue presente y activo en Fe y Alegr\u00eda, en nuestra Iglesia\u2026 y m\u00e1s all\u00e1\u2026 <\/div>\n","protected":false},"author":6,"featured_media":3605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[183],"tags":[552,400,554,556],"post_folder":[],"class_list":["post-3599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-abraham-reyes","tag-fe-y-alegria","tag-fundadores-de-fe-y-alegria","tag-patricia-garcia-de-reyes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gracias, Abraham y Patricia - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gracias, Abraham y Patricia - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"Al agradecer a Patricia y Abraham por su generosidad y su testimonio, estamos agradeciendo al Esp\u00edritu de Dios que sigue presente y activo en Fe y Alegr\u00eda, en nuestra Iglesia\u2026 y m\u00e1s all\u00e1\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-28T08:50:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-29T02:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29005840\/8-Foto-AyP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"554\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erika Briceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Briceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/\"},\"author\":{\"name\":\"Erika Briceno\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"headline\":\"Gracias, Abraham y Patricia\",\"datePublished\":\"2022-04-28T08:50:07+00:00\",\"dateModified\":\"2022-04-29T02:34:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/\"},\"wordCount\":697,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/29005840\\\/8-Foto-AyP.jpg\",\"keywords\":[\"Abraham Reyes\",\"Fe y Alegr\u00eda\",\"Fundadores de Fe y Alegr\u00eda\",\"Patricia Garc\u00eda de Reyes\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/\",\"name\":\"Gracias, Abraham y Patricia - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/29005840\\\/8-Foto-AyP.jpg\",\"datePublished\":\"2022-04-28T08:50:07+00:00\",\"dateModified\":\"2022-04-29T02:34:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/gracias-abraham-y-patricia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/29005840\\\/8-Foto-AyP.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/04\\\/29005840\\\/8-Foto-AyP.jpg\",\"width\":554,\"height\":445},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\",\"name\":\"Erika Briceno\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/comunfifya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gracias, Abraham y Patricia - Fe y Alegr\u00eda en Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/","og_locale":"es_ES","og_type":"article","og_title":"Gracias, Abraham y Patricia - Fe y Alegr\u00eda en Venezuela","og_description":"Al agradecer a Patricia y Abraham por su generosidad y su testimonio, estamos agradeciendo al Esp\u00edritu de Dios que sigue presente y activo en Fe y Alegr\u00eda, en nuestra Iglesia\u2026 y m\u00e1s all\u00e1\u2026","og_url":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2022-04-28T08:50:07+00:00","article_modified_time":"2022-04-29T02:34:37+00:00","og_image":[{"width":554,"height":445,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29005840\/8-Foto-AyP.jpg","type":"image\/jpeg"}],"author":"Erika Briceno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Erika Briceno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/"},"author":{"name":"Erika Briceno","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"headline":"Gracias, Abraham y Patricia","datePublished":"2022-04-28T08:50:07+00:00","dateModified":"2022-04-29T02:34:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/"},"wordCount":697,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29005840\/8-Foto-AyP.jpg","keywords":["Abraham Reyes","Fe y Alegr\u00eda","Fundadores de Fe y Alegr\u00eda","Patricia Garc\u00eda de Reyes"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/","url":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/","name":"Gracias, Abraham y Patricia - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29005840\/8-Foto-AyP.jpg","datePublished":"2022-04-28T08:50:07+00:00","dateModified":"2022-04-29T02:34:37+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/gracias-abraham-y-patricia\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29005840\/8-Foto-AyP.jpg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2022\/04\/29005840\/8-Foto-AyP.jpg","width":554,"height":445},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180","name":"Erika Briceno","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/comunfifya\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/3599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=3599"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/3599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/3605"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=3599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=3599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=3599"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=3599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}