{"id":4201,"date":"2023-12-04T13:50:45","date_gmt":"2023-12-04T13:50:45","guid":{"rendered":"https:\/\/dev-ve.feyalegria.org\/?p=4201"},"modified":"2023-12-04T13:50:45","modified_gmt":"2023-12-04T13:50:45","slug":"entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/","title":{"rendered":"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda<\/h1>\n<p>[\/vc_column_text][vc_single_image image=\u00bb4427&#8243; img_size=\u00bb880&#215;480&#8243; alignment=\u00bbcenter\u00bb onclick=\u00bblink_image\u00bb][vc_column_text]<span style=\"font-weight: 400\">La experiencia de los foros chats que se desarrolla desde la <\/span><span style=\"font-weight: 400\">serie de conversaciones<\/span><i><span style=\"font-weight: 400\"> \u201cEntre Pupitres y Tecnolog\u00edas\u201d<\/span><\/i><span style=\"font-weight: 400\">\u00a0representa para el <\/span><b>Centro de Formaci\u00f3n e Investigaci\u00f3n Padre Joaqu\u00edn<\/b><span style=\"font-weight: 400\"> una apuesta multimodal para la atenci\u00f3n de los docentes dentro y fuera de <strong>Fe y Alegr\u00eda Venezuela<\/strong> en materia pedag\u00f3gica, tecnol\u00f3gica, psicol\u00f3gica y de impacto social.\u00a0<\/span>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">De enero a diciembre de 2023 se realizaron 20 foros chats a trav\u00e9s de WhatsApp con temas diversos que buscan ayudar a los docentes a mejorar la atenci\u00f3n que brindan a sus estudiantes. Entre los temas tratados: la alianza necesaria entre padres y maestros, estrategias innovadoras para las \u00e1reas de formaci\u00f3n de educaci\u00f3n media general, la espiritualidad, la evaluaci\u00f3n por competencias, metodolog\u00edas para la educaci\u00f3n temprana, entre otros.<\/span>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">El espacio formativo comprende un momento sincr\u00f3nico para desarrollar el tema y un d\u00eda completo dedicado a compartir de saberes de forma asincr\u00f3nica entre docentes, organizadores y ponentes del foro chats.\u00a0\u00a0<\/span>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">Para desarrollar la jornada, los ponentes de cada tema se esfuerzan por generar un discurso enmarcado en la metodolog\u00eda de la Educaci\u00f3n Popular y cuidar la estructura dise\u00f1ada para el momento bajo la tutela del <strong>Centro de Formaci\u00f3n e Investigaci\u00f3n Padre Joaqu\u00edn<\/strong>, instancia que apoya los procesos formativos de todos los programas de <strong>Fe y Alegr\u00eda Venezuela<\/strong>.<\/span>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">La facilitaci\u00f3n de los 20 foro chats realizados durante el 2023 estuvo en manos de un grupo variado de expertos, entre ellos pedagogos del programa <strong>Fe y Alegr\u00eda Capacitaci\u00f3n<\/strong> y <strong>Fe y Alegr\u00eda Escuelas<\/strong>, la Universidad del Zulia, Universidad Nacional Experimental Rafael Mar\u00eda Baralt, Fundaci\u00f3n Empresas Polar, Universidad de Los Lagos (Chile), entre otras.<\/span>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">Los foros de esta serie contaron con 854 participantes. Este espacio cada vez gana m\u00e1s reconocimiento entre los docentes, quienes reconocen en la evaluaci\u00f3n de los foros chats que estos son \u201cexcelentes por su dedicaci\u00f3n, estructuraci\u00f3n y el contenido c\u00f3nsono a los desaf\u00edos de la educaci\u00f3n del futuro<\/span><i><span style=\"font-weight: 400\">\u201d.\u00a0<\/span><\/i>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">Este espacio innovador de formaci\u00f3n a distancia aprovechando el WhatsApp ha servido para \u201c\u2026mantener presente las orientaciones y sugerencias de cada tem\u00e1tica porque comparto con otros docentes y generamos nuevos conocimientos\u201d, seg\u00fan afirm\u00f3 un docente participante.\u00a0<\/span>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">Los foros chats\u00a0 son referencia de formaci\u00f3n virtual para <strong>Fe y Alegr\u00eda<\/strong> y muchos docentes del pa\u00eds que pueden aprovecharlo gracias a las sesiones sincr\u00f3nicas o revisando los materiales que resultan de cada formaci\u00f3n alojados en la secci\u00f3n \u201cSerie de Conversaciones\u201d de la p\u00e1gina web <\/span><a href=\"https:\/\/centrodeformacion.net\"><span style=\"font-weight: 400\">https:\/\/centrodeformacion.net<\/span><\/a><span style=\"font-weight: 400\"> disponible para todos los interesados.<\/span>[\/vc_column_text][vc_column_text]<strong>Por\u00a0<\/strong><b>Ram\u00f3n Labarca-Rinc\u00f3n<br \/>\n<\/b><span style=\"font-weight: 400\">Coordinador del \u00e1rea Investigaci\u00f3n<br \/>\n<\/span><span style=\"font-weight: 400\">Centro de Formaci\u00f3n e Investigaci\u00f3n Padre Joaqu\u00edn<\/span>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 180px\">La experiencia de los foro chats representa para el Centro de Formaci\u00f3n e Investigaci\u00f3n Padre Joaqu\u00edn una apuesta multimodal para atender a docentes dentro y fuera de Fe y Alegr\u00eda.<\/div>\n","protected":false},"author":6,"featured_media":4202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[183],"tags":[430,400,448],"post_folder":[],"class_list":["post-4201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cfipj","tag-fe-y-alegria","tag-venezuela"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"La experiencia de los foro chats representa para el Centro de Formaci\u00f3n e Investigaci\u00f3n Padre Joaqu\u00edn una apuesta multimodal para atender a docentes dentro y fuera de Fe y Alegr\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T13:50:45+00:00\" \/>\n<meta name=\"author\" content=\"Erika Briceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Briceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/\"},\"author\":{\"name\":\"Erika Briceno\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"headline\":\"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda\",\"datePublished\":\"2023-12-04T13:50:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/\"},\"wordCount\":573,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"CFIPJ\",\"Fe y Alegr\u00eda\",\"Venezuela\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/\",\"name\":\"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-12-04T13:50:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\",\"name\":\"Erika Briceno\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/comunfifya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/","og_locale":"es_ES","og_type":"article","og_title":"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","og_description":"La experiencia de los foro chats representa para el Centro de Formaci\u00f3n e Investigaci\u00f3n Padre Joaqu\u00edn una apuesta multimodal para atender a docentes dentro y fuera de Fe y Alegr\u00eda.","og_url":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2023-12-04T13:50:45+00:00","author":"Erika Briceno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Erika Briceno","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/"},"author":{"name":"Erika Briceno","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"headline":"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda","datePublished":"2023-12-04T13:50:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/"},"wordCount":573,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/#primaryimage"},"thumbnailUrl":"","keywords":["CFIPJ","Fe y Alegr\u00eda","Venezuela"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/","url":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/","name":"Entre pupitres y tecnolog\u00edas se forman los docentes de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-12-04T13:50:45+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/entre-pupitres-y-tecnologias-se-forman-los-docentes-de-fe-y-alegria\/#primaryimage","url":"","contentUrl":""},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180","name":"Erika Briceno","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/comunfifya\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/4201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=4201"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/4201\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=4201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=4201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=4201"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=4201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}