{"id":5334,"date":"2024-02-13T16:25:03","date_gmt":"2024-02-13T16:25:03","guid":{"rendered":"https:\/\/dev-ve.feyalegria.org\/?p=4719"},"modified":"2024-02-13T16:25:03","modified_gmt":"2024-02-13T16:25:03","slug":"la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/","title":{"rendered":"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda<\/h1>\n<p>[\/vc_column_text][vc_column_text]<span style=\"font-weight: 400\">A prop\u00f3sito de conmemorarse este 13 de febrero el D\u00eda Mundial de la Radio, <\/span><b>Fe y Alegr\u00eda<\/b><span style=\"font-weight: 400\"> va rumbo a los 50 a\u00f1os impulsando la educaci\u00f3n a trav\u00e9s de las ondas hertzianas, siendo pionera en la utilizaci\u00f3n de la radio como herramienta educativa, llegando a miles de personas en zonas rurales y de dif\u00edcil acceso donde la educaci\u00f3n formal es limitada.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Una de las recientes iniciativas recientes m\u00e1s destacadas de <\/span><b>Fe y Alegr\u00eda<\/b><span style=\"font-weight: 400\"> es <\/span><b>La Escuela en la Radio (LEER)<\/b><span style=\"font-weight: 400\">.\u00a0 Es una alianza entre <\/span><b>Fe y Alegr\u00eda Escuela<\/b><span style=\"font-weight: 400\">, <\/span><b>Fe y Alegr\u00eda Educomunicaci\u00f3n<\/b><span style=\"font-weight: 400\"> y el equipo pedag\u00f3gico que surgi\u00f3 en abril de 2020 como respuesta al confinamiento por la COVID-19.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Esta experiencia form\u00f3 parte de una estrategia para reforzar las tem\u00e1ticas de lenguaje y comunicaci\u00f3n, el pensamiento l\u00f3gico matem\u00e1tico, la inteligencia emocional, los valores, la tecnolog\u00eda y la ciudadan\u00eda; empleando la radio como medio para llegar al estudiantado que se encontraba en casa con una gu\u00eda de actividades proporcionadas por UNICEF.<\/span>[\/vc_column_text][vc_single_image image=\u00bb4720&#8243; img_size=\u00bb800&#215;400&#8243; onclick=\u00bblink_image\u00bb][vc_column_text]<\/p>\n<h4><b>La magia de la radio\u00a0<\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">En un primer momento, fue producido para entretener, informar y educar a los ni\u00f1os y ni\u00f1as de <\/span><span style=\"font-weight: 400\">educaci\u00f3n inicial hasta 6to grado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Una docente prepar\u00f3 un programa con secciones como: <em>\u00bfSab\u00edas qu\u00e9?<\/em>, trivias, ejercicios de matem\u00e1ticas, normas ortogr\u00e1ficas, promoci\u00f3n de la escritura creativa y promoci\u00f3n de la lectura con la secci\u00f3n <em>\u201cCuento que te cuento un cuento\u201d.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Entre las din\u00e1micas establecidas se les propon\u00eda a los estudiantes: cambiar el final, reflexionar sobre el mensaje del cuento, ilustrar, elaborar c\u00f3mics, sobre la historia escuchada, entre otras actividades.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Cada programa contaba con ejercicios de respiraci\u00f3n y relajaci\u00f3n. Durante esta temporada, el equipo responsable de LEER recibi\u00f3 formaci\u00f3n en producci\u00f3n radiof\u00f3nica. Cabe destacar que estudiantes de educaci\u00f3n inicial y en la segunda etapa participaron en la producci\u00f3n del programa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b>Chispa que contagi\u00f3\u00a0<\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Posteriormente, se incorporaron docentes para producir el programa.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Un responsable por etapa: Educaci\u00f3n inicial, denominados \u201cLos Chipilines\u201d; primera etapa, de primer a tercer grado llamados \u201cLos Pequegigantes\u201d; y segunda etapa identificados como \u201cLos Gigantes\u201d, estudiantes de 4to a 6to grado.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Semanalmente se cumpl\u00eda la planificaci\u00f3n enviada por la coordinaci\u00f3n pedag\u00f3gica del programa <strong>Fe y Alegr\u00eda Escuela<\/strong>, apoyada en las gu\u00edas de actividades de UNICEF que ten\u00edan los estudiantes.<\/span>[\/vc_column_text][vc_column_text]<\/p>\n<h4><b>LEER,<\/b><b> un programa que se adapta y evoluciona<\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Cuando las clases vuelven a la presencialidad, LEER vuelve a reforzar las \u00e1reas b\u00e1sicas en cada etapa escolar: entretiene, informa y educa.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Con alguna participaci\u00f3n de ni\u00f1os se abordaron otros temas como la amistad, la salud oral, ocupaci\u00f3n del tiempo libre, saludos, entre otros.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">La producci\u00f3n del programa se volvi\u00f3 interesante usando el tel\u00e9fono inteligente, la creaci\u00f3n\u00a0<\/span><span style=\"font-weight: 400\">artesanal de un estudio radial en casa, con almohadas, laptop y celular,\u00a0 una manera pr\u00e1ctica de hacer radio.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Hasta la actualidad, la familia participa en el programa, como adultos mayores que se han comunicado, dando respuesta a las trivias. Asimismo, una ni\u00f1a de la localidad de El Tigre manifest\u00f3 que se adue\u00f1a de la radio a partir de las 4:00 de la tarde.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Hay casos de ni\u00f1os que han enviado al WhatsApp exposiciones que prepararon para sus clases y han querido compartirlas en el programa. Fue y sigue representando una oportunidad.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Otra de las an\u00e9cdotas significativas fue cuando se habl\u00f3 en el programa\u00a0 de los sitios de inter\u00e9s en el estado Lara y una ni\u00f1a manifest\u00f3 por WhatsApp que su madre era de Lara y estaba muy contenta por escuchar cosas lindas de la tierra de su mam\u00e1. Adem\u00e1s, destac\u00f3 que le encantaba escuchar la canci\u00f3n: \u201cEnanos y gigantes\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Por otra parte, se recibi\u00f3 el testimonio de una ni\u00f1a, que con gran alegr\u00eda cont\u00f3 que a las 4:00 de la tarde invitaba a los vecinos al patio de su casa para o\u00edr el programa y realizar juntos las actividades sugeridas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">La radio es una ventana que invita al encuentro, a la reflexi\u00f3n y genera cambios de actitud. La radio es una herramienta poderosa para aprender, <\/span><span style=\"font-weight: 400\">especialmente en contextos desafiantes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Este programa ha permitido que miles de personas contin\u00faen aprendiendo y desarroll\u00e1ndose a pesar de las dificultades.<\/span>[\/vc_column_text][vc_column_text]<b>Por Lecgisia Torres de Krisch | Coproductora del programa \u201cLa Escuela en la Radio\u201d<\/b>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Fe y Alegr\u00eda va rumbo a los 50 a\u00f1os impulsando la educaci\u00f3n a trav\u00e9s de las ondas hertzianas, siendo pionera en usar la radio como herramienta educativa.<\/p>\n","protected":false},"author":6,"featured_media":4720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[183],"tags":[400,717,719,721],"post_folder":[],"class_list":["post-5334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-fe-y-alegria","tag-la-escuela-en-la-radio","tag-leer","tag-radio-fe-y-alegria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"Fe y Alegr\u00eda va rumbo a los 50 a\u00f1os impulsando la educaci\u00f3n a trav\u00e9s de las ondas hertzianas, siendo pionera en usar la radio como herramienta educativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-13T16:25:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/02\/13202502\/APURE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"3000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Erika Briceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Briceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/\"},\"author\":{\"name\":\"Erika Briceno\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"headline\":\"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda\",\"datePublished\":\"2024-02-13T16:25:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/\"},\"wordCount\":841,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/13202502\\\/APURE.png\",\"keywords\":[\"Fe y Alegr\u00eda\",\"La Escuela en la Radio\",\"LEER\",\"Radio Fe y Alegr\u00eda\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/\",\"name\":\"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/13202502\\\/APURE.png\",\"datePublished\":\"2024-02-13T16:25:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/13202502\\\/APURE.png\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/13202502\\\/APURE.png\",\"width\":3000,\"height\":3000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\",\"name\":\"Erika Briceno\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/comunfifya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/","og_locale":"es_ES","og_type":"article","og_title":"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","og_description":"Fe y Alegr\u00eda va rumbo a los 50 a\u00f1os impulsando la educaci\u00f3n a trav\u00e9s de las ondas hertzianas, siendo pionera en usar la radio como herramienta educativa.","og_url":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2024-02-13T16:25:03+00:00","og_image":[{"width":3000,"height":3000,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/02\/13202502\/APURE.png","type":"image\/png"}],"author":"Erika Briceno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Erika Briceno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/"},"author":{"name":"Erika Briceno","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"headline":"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda","datePublished":"2024-02-13T16:25:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/"},"wordCount":841,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/02\/13202502\/APURE.png","keywords":["Fe y Alegr\u00eda","La Escuela en la Radio","LEER","Radio Fe y Alegr\u00eda"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/","url":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/","name":"La Escuela en la Radio: un ejemplo de innovaci\u00f3n educativa de Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/02\/13202502\/APURE.png","datePublished":"2024-02-13T16:25:03+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/la-escuela-en-la-radio-un-ejemplo-de-innovacion-educativa-de-fe-y-alegria\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/02\/13202502\/APURE.png","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/02\/13202502\/APURE.png","width":3000,"height":3000},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180","name":"Erika Briceno","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/comunfifya\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/5334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=5334"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/5334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/4720"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=5334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=5334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=5334"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=5334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}