{"id":8567,"date":"2024-12-16T20:54:14","date_gmt":"2024-12-16T20:54:14","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=8567"},"modified":"2024-12-16T20:55:45","modified_gmt":"2024-12-16T20:55:45","slug":"joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/","title":{"rendered":"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h1><b>Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas<\/b><\/h1>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_single_image image=\u00bb8571&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right;\"><strong>Graciela Portillo | <\/strong><em>Equipo de Comunicaciones Fe y Alegr\u00eda Venezuela<\/em><strong><em><br \/>\n<\/em><\/strong><\/p>\n<p>[\/vc_column_text][vc_separator][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\">Joseph P\u00e9rez, estudiante de octavo grado de la Unidad Educativa Colegio Fe y Alegr\u00eda La Consolaci\u00f3n, ubicada en el estado Bol\u00edvar, fue reconocido con una menci\u00f3n honor\u00edfica por su destacada y constante participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas Leibniz (LIMOC) 2024, realizada en Indonesia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">este evento, la delegaci\u00f3n venezolana estuvo representada por talentosos j\u00f3venes: Ibrahim Rahwan Falah, de la U.E. Colegio Los Pr\u00f3ceres; Axel Hern\u00e1ndez del L.N. Eduardo Oxford; Enrique Gabriel Hern\u00e1ndez, de la U.E.C. Iberoamericano; y Joseph P\u00e9rez, de nuestra instituci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">De manera virtual, se enfrentaron a representantes de once pa\u00edses, entre ellos: Bolivia, Bulgaria, Guatemala, Hong Kong, Indonesia, M\u00e9xico, Mongolia, Filipinas y Tailandia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Esta representaci\u00f3n logr\u00f3 un destacado desempe\u00f1o, obteniendo una medalla de plata, una de bronce y una menci\u00f3n honor\u00edfica. Ibrahim Rahwan Falah, representante de Venezuela en la categor\u00eda A (cuarto, quinto y sexto grado), conquist\u00f3 la medalla de plata.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Por su parte, Axel Hern\u00e1ndez, del L.N Eduardo Oxford, obtuvo la medalla de bronce en la categor\u00eda B (s\u00e9ptimo a noveno grado), categor\u00eda en la que tambi\u00e9n particip\u00f3 Joseph P\u00e9rez, quien recibi\u00f3 una menci\u00f3n honor\u00edfica. Enrique Gabriel Hern\u00e1ndez, de la U.E.C. Iberoamericano, fue finalista de la justa ol\u00edmpica.<\/p>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb8568&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb8570&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb8569&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][\/vc_column_inner][\/vc_row_inner][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\">Varios de estos j\u00f3venes pertenecen al semillero cient\u00edfico destacado del Ministerio del Poder Popular para la Ciencia y Tecnolog\u00eda, algunos de ellos preparados en Fundacite Bol\u00edvar a cargo del Ing. Luis C\u00e1rdenas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Es importante destacar que, en agosto de este mismo a\u00f1o, Joseph P\u00e9rez hab\u00eda obtenido <strong><a href=\"https:\/\/www.feyalegria.org\/venezuela\/estudiante-de-fe-y-alegria-brillo-con-luz-propia-en-las-olimpiadas-mundiales-de-matematicas-2024\/\"><u>una medalla de bronce en las Olimpiadas Mundiales de J\u00f3venes Matem\u00e1ticos 2024 (WYMO)<\/u><\/a><\/strong>, tambi\u00e9n celebradas en Indonesia.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Desde Fe y Alegr\u00eda Venezuela, extendemos nuestras m\u00e1s sinceras felicitaciones a Joseph, a todo el personal docente, aliados y familiares que han contribuido a su formaci\u00f3n y a su destacada participaci\u00f3n en estas competencias internacionales. \u00a1Joseph es un orgullo para Fe y Alegr\u00eda!<\/p>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right;\"><strong><em>Caracas, 16 de diciembre de 2024<\/em><\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 145px\">Estudiante de Fe y Alegr\u00eda fue reconocido con una menci\u00f3n honor\u00edfica por su destacada y constante participaci\u00f3n en la Olimpiada Internacional&#8230;<\/div>\n","protected":false},"author":6,"featured_media":8571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[11,183],"tags":[400,983],"post_folder":[],"class_list":["post-8567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela","category-noticias","tag-fe-y-alegria","tag-olimpiadas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"description\" content=\"Estudiante de Fe y Alegr\u00eda fue reconocido con menci\u00f3n honor\u00edfica por su destacada participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"Estudiante de Fe y Alegr\u00eda fue reconocido con menci\u00f3n honor\u00edfica por su destacada participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T20:54:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T20:55:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/12\/16203237\/Joseph-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erika Briceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Briceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/\"},\"author\":{\"name\":\"Erika Briceno\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"headline\":\"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas\",\"datePublished\":\"2024-12-16T20:54:14+00:00\",\"dateModified\":\"2024-12-16T20:55:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/\"},\"wordCount\":549,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/16203237\\\/Joseph-1.jpg\",\"keywords\":[\"Fe y Alegr\u00eda\",\"Olimpiadas\"],\"articleSection\":[\"Escuela\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/\",\"name\":\"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/16203237\\\/Joseph-1.jpg\",\"datePublished\":\"2024-12-16T20:54:14+00:00\",\"dateModified\":\"2024-12-16T20:55:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"description\":\"Estudiante de Fe y Alegr\u00eda fue reconocido con menci\u00f3n honor\u00edfica por su destacada participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/16203237\\\/Joseph-1.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/12\\\/16203237\\\/Joseph-1.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Joseph P\u00e9rez, estudiante de octavo grado de la Unidad Educativa Colegio Fe y Alegr\u00eda La Consolaci\u00f3n, estado Bol\u00edvar.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\",\"name\":\"Erika Briceno\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/comunfifya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas - Fe y Alegr\u00eda en Venezuela","description":"Estudiante de Fe y Alegr\u00eda fue reconocido con menci\u00f3n honor\u00edfica por su destacada participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/","og_locale":"es_ES","og_type":"article","og_title":"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas - Fe y Alegr\u00eda en Venezuela","og_description":"Estudiante de Fe y Alegr\u00eda fue reconocido con menci\u00f3n honor\u00edfica por su destacada participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas","og_url":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2024-12-16T20:54:14+00:00","article_modified_time":"2024-12-16T20:55:45+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/12\/16203237\/Joseph-1.jpg","type":"image\/jpeg"}],"author":"Erika Briceno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Erika Briceno","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/"},"author":{"name":"Erika Briceno","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"headline":"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas","datePublished":"2024-12-16T20:54:14+00:00","dateModified":"2024-12-16T20:55:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/"},"wordCount":549,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/12\/16203237\/Joseph-1.jpg","keywords":["Fe y Alegr\u00eda","Olimpiadas"],"articleSection":["Escuela","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/","url":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/","name":"Joseph P\u00e9rez, estudiante de Fe y Alegr\u00eda, conquista menci\u00f3n honor\u00edfica en la Olimpiada Internacional de Matem\u00e1ticas - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/12\/16203237\/Joseph-1.jpg","datePublished":"2024-12-16T20:54:14+00:00","dateModified":"2024-12-16T20:55:45+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"description":"Estudiante de Fe y Alegr\u00eda fue reconocido con menci\u00f3n honor\u00edfica por su destacada participaci\u00f3n en la Olimpiada Internacional de Matem\u00e1ticas","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/joseph-perez-estudiante-de-fe-y-alegria-conquista-mencion-honorifica-en-la-olimpiada-internacional-de-matematicas\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/12\/16203237\/Joseph-1.jpg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2024\/12\/16203237\/Joseph-1.jpg","width":1200,"height":900,"caption":"Joseph P\u00e9rez, estudiante de octavo grado de la Unidad Educativa Colegio Fe y Alegr\u00eda La Consolaci\u00f3n, estado Bol\u00edvar."},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180","name":"Erika Briceno","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/comunfifya\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/8567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=8567"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/8567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/8571"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=8567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=8567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=8567"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=8567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}