{"id":8689,"date":"2025-01-16T00:08:52","date_gmt":"2025-01-16T00:08:52","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=8689"},"modified":"2025-01-28T12:25:41","modified_gmt":"2025-01-28T12:25:41","slug":"cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/","title":{"rendered":"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<h1><b>Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda<\/b><\/h1>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_single_image image=\u00bb8690&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right;\"><strong>Yorgelis Cogollo<\/strong>\u00a0| <em>Referente de Comunicaci\u00f3n del Programa Escuelas<\/em><\/p>\n<p>[\/vc_column_text][vc_separator][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\">En un mundo cada vez m\u00e1s tecnol\u00f3gico, <strong>los docentes buscan constantemente nuevas herramientas para preparar a sus estudiantes para el futuro<\/strong>. Una de estas \u00e1reas en constante crecimiento es la rob\u00f3tica, la programaci\u00f3n y la electr\u00f3nica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><br \/>\nCristina Berm\u00fadez, maestra y coordinadora de las Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n (TIC) en la escuela <strong>Fe y Alegr\u00eda Virgen Ni\u00f1a de Caracas<\/strong>, es un ejemplo de c\u00f3mo la formaci\u00f3n continua puede transformar la pr\u00e1ctica docente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><br \/>\nDesde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa, lo que le ha permitido fortalecer sus habilidades y ofrecer a sus estudiantes experiencias de aprendizaje innovadoras. <strong>Con vocaci\u00f3n y sin quedarse atr\u00e1s<\/strong>, Cristina ha potenciado su carrera a trav\u00e9s de los planes educativos que ofrece Fe y Alegr\u00eda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><br \/>\nLa tecnolog\u00eda para ella no ha sido un campo de fuerza que le impida ejercer su profesi\u00f3n, sino que es una herramienta para poder seguir potenciando sus habilidades y transmitir sus m\u00e9todos de ense\u00f1anza desde otro enfoque.<\/span><\/p>\n<h3><span style=\"font-size: 14px;\"><br \/>\nUn proyecto de rob\u00f3tica para transformar la educaci\u00f3n<\/span><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8692 alignright\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234940\/Escuelas-38-3-300x225.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234940\/Escuelas-38-3-300x225.jpg 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234940\/Escuelas-38-3-1024x768.jpg 1024w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234940\/Escuelas-38-3-768x576.jpg 768w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234940\/Escuelas-38-3.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Junto a sus colegas y con el apoyo de Profuturo, una organizaci\u00f3n dedicada a potenciar la educaci\u00f3n digital, Cristina particip\u00f3 en un proyecto para construir un prototipo de robot con sus estudiantes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><br \/>\nEn una entrevista realizada por Profuturo, Cristina destac\u00f3 la importancia de los valores humanos cristianos en Fe y Alegr\u00eda, los cuales son fundamentales para motivar tanto a docentes como a estudiantes. Adem\u00e1s, resalt\u00f3 el trabajo colaborativo y el apoyo mutuo como claves para el \u00e9xito de este tipo de proyectos.<\/span><\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cEste trabajo es compartido y ha tenido una buena apreciaci\u00f3n por parte de los estudiantes\u201d<\/strong>, asegur\u00f3 Cristina, que destaca que tienen un \u201cplus\u201d, para que los docentes y los estudiantes logren los objetivos propuestos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">La capacitaci\u00f3n recibida por los docentes incluy\u00f3 diversos ejes tem\u00e1ticos, como la implementaci\u00f3n de las TIC en el aula, la formaci\u00f3n docente, la formaci\u00f3n de la comunidad y la sostenibilidad, la red de promotores, acompa\u00f1amiento y seguimiento; y sistematizaci\u00f3n de buenas pr\u00e1cticas. El objetivo era brindar a los docentes las herramientas necesarias para integrar la tecnolog\u00eda en sus pr\u00e1cticas pedag\u00f3gicas de manera efectiva.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Cada suma de esfuerzos entre los docentes y estudiantes es una oportunidad de crecer juntos hacia nuevos objetivos que fortalezcan la educaci\u00f3n en todas las \u00e1reas, Cristina por ejemplo, se define como una maestra emp\u00e1tica y constante; <strong>para la docente, el amor va de primera mano para que sus estudiantes puedan nutrir sus conocimientos.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">La perseverancia como motor de cambio<\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Para Cristina la perseverancia es el motor que impulsa cada d\u00eda a hacer lo que nos apasiona. Es aportar un granito de arena para la construcci\u00f3n de un pa\u00eds donde todos somos necesarios e importantes, los obst\u00e1culos y los desaf\u00edos se superan con paciencia y formaci\u00f3n. Son pruebas que se presentan para aprender.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8691 alignleft\" src=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234937\/Escuelas-38-2-300x225.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234937\/Escuelas-38-2-300x225.jpg 300w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234937\/Escuelas-38-2-1024x768.jpg 1024w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234937\/Escuelas-38-2-768x576.jpg 768w, https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234937\/Escuelas-38-2.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\u201cLo que se aprende jam\u00e1s se olvida\u201d, es aquella frase que muchas veces hacen \u00e9nfasis los padres y abuelos, y es que al finalizar cada etapa, los estudiantes siempre recordar\u00e1n a esa maestra que le dio la base al estudiante y lo motiv\u00f3 en alg\u00fan momento a perseguir sus sue\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">La experiencia de Cristina, es un ejemplo de c\u00f3mo la formaci\u00f3n continua y la pasi\u00f3n por la ense\u00f1anza pueden transformar la educaci\u00f3n. Al integrar la rob\u00f3tica y otras tecnolog\u00edas en sus clases, Cristina est\u00e1 preparando a sus estudiantes para un futuro cada vez m\u00e1s digital y complejo.<\/p>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right;\"><strong><em>Caracas, 16 de enero de 2025<\/em><\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 160px\">Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en iniciativas de formaci\u00f3n en rob\u00f3tica educativa.<\/div>\n","protected":false},"author":6,"featured_media":8690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[746,11,183],"tags":[398,400,893],"post_folder":[],"class_list":["post-8689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin-interno","category-escuela","category-noticias","tag-dia-del-maestro","tag-fe-y-alegria","tag-robotica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"description\" content=\"Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T00:08:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T12:25:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234935\/Escuelas-38-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erika Briceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Briceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/\"},\"author\":{\"name\":\"Erika Briceno\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"headline\":\"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda\",\"datePublished\":\"2025-01-16T00:08:52+00:00\",\"dateModified\":\"2025-01-28T12:25:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/\"},\"wordCount\":749,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/01\\\/15234935\\\/Escuelas-38-1.jpg\",\"keywords\":[\"D\u00eda del Maestro\",\"Fe y Alegr\u00eda\",\"Rob\u00f3tica\"],\"articleSection\":[\"Bolet\u00edn Interno\",\"Escuela\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/\",\"name\":\"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/01\\\/15234935\\\/Escuelas-38-1.jpg\",\"datePublished\":\"2025-01-16T00:08:52+00:00\",\"dateModified\":\"2025-01-28T12:25:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"description\":\"Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/01\\\/15234935\\\/Escuelas-38-1.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/01\\\/15234935\\\/Escuelas-38-1.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\",\"name\":\"Erika Briceno\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/comunfifya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","description":"Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/","og_locale":"es_ES","og_type":"article","og_title":"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","og_description":"Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa","og_url":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2025-01-16T00:08:52+00:00","article_modified_time":"2025-01-28T12:25:41+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234935\/Escuelas-38-1.jpg","type":"image\/jpeg"}],"author":"Erika Briceno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Erika Briceno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/"},"author":{"name":"Erika Briceno","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"headline":"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda","datePublished":"2025-01-16T00:08:52+00:00","dateModified":"2025-01-28T12:25:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/"},"wordCount":749,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234935\/Escuelas-38-1.jpg","keywords":["D\u00eda del Maestro","Fe y Alegr\u00eda","Rob\u00f3tica"],"articleSection":["Bolet\u00edn Interno","Escuela","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/","url":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/","name":"Cristina Berm\u00fadez: La maestra que promueve la rob\u00f3tica en Fe y Alegr\u00eda - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234935\/Escuelas-38-1.jpg","datePublished":"2025-01-16T00:08:52+00:00","dateModified":"2025-01-28T12:25:41+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"description":"Desde que lleg\u00f3 a Fe y Alegr\u00eda Virgen Ni\u00f1a en 2019, Cristina ha participado en diversas iniciativas de formaci\u00f3n en rob\u00f3tica educativa","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/cristina-bermudez-la-maestra-que-promueve-la-robotica-en-fe-y-alegria\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234935\/Escuelas-38-1.jpg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/01\/15234935\/Escuelas-38-1.jpg","width":1200,"height":900},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180","name":"Erika Briceno","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/comunfifya\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/8689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=8689"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/8689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/8690"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=8689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=8689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=8689"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=8689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}