{"id":9969,"date":"2025-05-30T03:22:40","date_gmt":"2025-05-30T03:22:40","guid":{"rendered":"https:\/\/www.feyalegria.org\/venezuela\/?p=9969"},"modified":"2025-06-05T13:29:22","modified_gmt":"2025-06-05T13:29:22","slug":"proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible","status":"publish","type":"post","link":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/","title":{"rendered":"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<h1><b>Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible<\/b><\/h1>\n<p>[\/vc_column_text][vc_separator css=\u00bb\u00bb][vc_single_image image=\u00bb9970&#8243; img_size=\u00bbfull\u00bb add_caption=\u00bbyes\u00bb css=\u00bb\u00bb][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right\"><strong>German Osorio<\/strong> | <em>Referente de Comunicaci\u00f3n de Fe y Alegr\u00eda Capacitaci\u00f3n<\/em><\/p>\n<p style=\"text-align: right\"><strong>Olivia Villanueva<\/strong> | <em>Responsable de centro de Capacitaci\u00f3n Padre Jos\u00e9 Mar\u00eda Velaz<\/em><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: justify\">El centro de capacitaci\u00f3n Padre Jos\u00e9 Mar\u00eda V\u00e9laz, ubicado en el municipio Valmore Rodriguez del estado Zulia, junto a Fe y Alegr\u00eda Servicios uni\u00f3 esfuerzos para impulsar el Proyecto Ra\u00edces. Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, tiene como objetivo primordial fortalecer las capacidades productivas de la regi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Este innovador programa que se desarrolla desde julio de 2024, busca potenciar tres cadenas de valor fundamentales: caraotas, pollos de engorde y gallinas ponedoras. Como parte de esta estrategia, se ha seleccionado un centro de producci\u00f3n para especializarse en el cultivo de caraotas. En una parcela de 0.50 hect\u00e1reas, se han llevado a cabo intensas labores que incluyen la limpieza de maleza, cercado perimetral, preparaci\u00f3n del terreno con cal agr\u00edcola y materia org\u00e1nica, adem\u00e1s del rastreo del suelo para asegurar su \u00f3ptima condici\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Entre los avances m\u00e1s significativos de este proyecto, destaca la instalaci\u00f3n de un eficiente sistema de riego por goteo, crucial para garantizar el adecuado desarrollo de las semillas. La siembra se realiz\u00f3 con \u00e9xito y, durante los \u00faltimos tres meses, el equipo ha trabajado diligentemente en la aplicaci\u00f3n de fertilizantes y el control de plagas mediante insecticidas, asegurando as\u00ed la calidad del cultivo.<\/p>\n<p>&nbsp;<\/p>\n<h3>Del campo al mercado<\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Actualmente, el proyecto se encuentra en la fase de cosecha y secado. Este paso es fundamental para preparar los productos frescos y de alta calidad para su comercializaci\u00f3n, coronando con satisfacci\u00f3n el esfuerzo invertido.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">El equipo responsable del centro, conformado por Olivia Villanueva, Danelys Silva, Fimbert Prince y Marco Leal, expresa su profundo entusiasmo y orgullo por la exitosa ejecuci\u00f3n de este proyecto.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Para las comunidades, \u00abRa\u00edces\u00bb representa un beneficio directo para las parroquias Rafael Urdaneta, La Victoria y Ra\u00fal Cuenca. La iniciativa promueve la producci\u00f3n local de alimentos frescos y de calidad, pensados para ser ofrecidos directamente al consumidor, acortando as\u00ed la cadena de distribuci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Olivia Villanueva,expres\u00f3 su satisfacci\u00f3n y gratitud con Dios por los avances del proyecto en el centro de capacitaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">\u201cEsto sigue evolucionando de la mejor manera. La producci\u00f3n beneficiar\u00e1 directamente a las tres parroquias del municipio: Rafael Urdaneta, La Victoria y Ra\u00fal Cuenca. Nuestros productos ser\u00e1n entregados directamente al consumidor\u201d, afirm\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<h3>Hacia la sostenibilidad local<\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">A trav\u00e9s del Proyecto \u201cRA\u00cdCES\u201d, nuestro programa de capacitaci\u00f3n se posiciona como un verdadero motor de transformaci\u00f3n agr\u00edcola en Venezuela. Esta iniciativa no solo fortalece las ra\u00edces de la econom\u00eda local, sino que tambi\u00e9n impulsa el futuro de nuestra tierra al capacitar a j\u00f3venes y adultos en pr\u00e1cticas agropecuarias innovadoras y efectivas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">Con este proyecto, somos un puente que conecta a las comunidades con nuevas oportunidades de aprendizaje y desarrollo t\u00e9cnico, abriendo caminos hacia un modelo de agricultura sostenible, resiliente y con identidad propia. Cada sembrad\u00edo, cada semilla plantada y cada esfuerzo realizado hoy, sientan las bases para un ma\u00f1ana m\u00e1s pr\u00f3spero y autosuficiente para nuestro pa\u00eds.<\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00bb\u00bb][\/vc_column_text][vc_column_inner alignment=\u00bbcenter\u00bb][\/vc_column_inner][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9971&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9972&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00bb\u00bb]<\/p>\n<p style=\"text-align: right\"><strong>Caracas, 30 de mayo de 2025<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div style=\"height: 265px\">Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas. <\/div>\n","protected":false},"author":6,"featured_media":9970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[746,1125],"tags":[634,400,516],"post_folder":[],"class_list":["post-9969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin-interno","category-capacitacion","tag-capacitacion","tag-fe-y-alegria","tag-raices"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"description\" content=\"Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:description\" content=\"Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T03:22:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T13:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/05\/30031142\/RAICES_web-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erika Briceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Briceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/\"},\"author\":{\"name\":\"Erika Briceno\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"headline\":\"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible\",\"datePublished\":\"2025-05-30T03:22:40+00:00\",\"dateModified\":\"2025-06-05T13:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/\"},\"wordCount\":692,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/30031142\\\/RAICES_web-1.jpg\",\"keywords\":[\"Capacitaci\u00f3n\",\"Fe y Alegr\u00eda\",\"Ra\u00edces\"],\"articleSection\":[\"Bolet\u00edn Interno\",\"capacitaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/\",\"name\":\"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/30031142\\\/RAICES_web-1.jpg\",\"datePublished\":\"2025-05-30T03:22:40+00:00\",\"dateModified\":\"2025-06-05T13:29:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\"},\"description\":\"Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/30031142\\\/RAICES_web-1.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pugrm67vf9n7.cloudfront.net\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/30031142\\\/RAICES_web-1.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#\\\/schema\\\/person\\\/fcd504e06f93320841b99f79f3ab0180\",\"name\":\"Erika Briceno\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/author\\\/comunfifya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible - Fe y Alegr\u00eda en Venezuela","description":"Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/","og_locale":"es_ES","og_type":"article","og_title":"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible - Fe y Alegr\u00eda en Venezuela","og_description":"Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas.","og_url":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","article_published_time":"2025-05-30T03:22:40+00:00","article_modified_time":"2025-06-05T13:29:22+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/05\/30031142\/RAICES_web-1.jpg","type":"image\/jpeg"}],"author":"Erika Briceno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Erika Briceno","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/#article","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/"},"author":{"name":"Erika Briceno","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"headline":"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible","datePublished":"2025-05-30T03:22:40+00:00","dateModified":"2025-06-05T13:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/"},"wordCount":692,"commentCount":0,"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/05\/30031142\/RAICES_web-1.jpg","keywords":["Capacitaci\u00f3n","Fe y Alegr\u00eda","Ra\u00edces"],"articleSection":["Bolet\u00edn Interno","capacitaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/","url":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/","name":"Proyecto Ra\u00edces de Fe y Alegr\u00eda: cultivando un futuro sostenible - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/#primaryimage"},"image":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/05\/30031142\/RAICES_web-1.jpg","datePublished":"2025-05-30T03:22:40+00:00","dateModified":"2025-06-05T13:29:22+00:00","author":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180"},"description":"Esta iniciativa, centrada en la recuperaci\u00f3n agroalimentaria integral con enfoque sostenible, busca fortalecer capacidades productivas.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.feyalegria.org\/venezuela\/proyecto-raices-de-fe-y-alegria-cultivando-un-futuro-sostenible\/#primaryimage","url":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/05\/30031142\/RAICES_web-1.jpg","contentUrl":"https:\/\/d3pugrm67vf9n7.cloudfront.net\/wp-content\/uploads\/sites\/4\/2025\/05\/30031142\/RAICES_web-1.jpg","width":1200,"height":900},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.feyalegria.org\/venezuela\/#\/schema\/person\/fcd504e06f93320841b99f79f3ab0180","name":"Erika Briceno","url":"https:\/\/www.feyalegria.org\/venezuela\/author\/comunfifya\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/9969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/comments?post=9969"}],"version-history":[{"count":0,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts\/9969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media\/9970"}],"wp:attachment":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/media?parent=9969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/categories?post=9969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags?post=9969"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/post_folder?post=9969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}