{"id":1378,"count":1,"description":"","link":"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/","name":"Olimpiadas de Lengua","slug":"olimpiadas-de-lengua","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olimpiadas de Lengua Archives - Fe y Alegr\u00eda en Venezuela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olimpiadas de Lengua Archives - Fe y Alegr\u00eda en Venezuela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/\" \/>\n<meta property=\"og:site_name\" content=\"Fe y Alegr\u00eda en Venezuela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/tag\\\/olimpiadas-de-lengua\\\/\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/tag\\\/olimpiadas-de-lengua\\\/\",\"name\":\"Olimpiadas de Lengua Archives - Fe y Alegr\u00eda en Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/#website\",\"url\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/\",\"name\":\"Fe y Alegr\u00eda en Venezuela\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.feyalegria.org\\\/venezuela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olimpiadas de Lengua Archives - Fe y Alegr\u00eda en Venezuela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/","og_locale":"es_ES","og_type":"article","og_title":"Olimpiadas de Lengua Archives - Fe y Alegr\u00eda en Venezuela","og_url":"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/","og_site_name":"Fe y Alegr\u00eda en Venezuela","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/","url":"https:\/\/www.feyalegria.org\/venezuela\/tag\/olimpiadas-de-lengua\/","name":"Olimpiadas de Lengua Archives - Fe y Alegr\u00eda en Venezuela","isPartOf":{"@id":"https:\/\/www.feyalegria.org\/venezuela\/#website"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/www.feyalegria.org\/venezuela\/#website","url":"https:\/\/www.feyalegria.org\/venezuela\/","name":"Fe y Alegr\u00eda en Venezuela","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feyalegria.org\/venezuela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags\/1378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.feyalegria.org\/venezuela\/wp-json\/wp\/v2\/posts?tags=1378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}